{"id":517,"date":"2021-09-09T07:40:47","date_gmt":"2021-09-09T07:40:47","guid":{"rendered":"https:\/\/qi107.qodeinteractive.com\/?p=517"},"modified":"2021-09-09T07:40:47","modified_gmt":"2021-09-09T07:40:47","slug":"virgin-gorda","status":"publish","type":"post","link":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/","title":{"rendered":"Virgin gorda"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"517\" class=\"elementor elementor-517\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c190c0 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"7c190c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6f306c qodef-sticky-column--no\" data-id=\"b6f306c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35c8773 elementor-widget elementor-widget-text-editor\" data-id=\"35c8773\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alia mucius ex nam, ea facer liber usu, est aliquam eu platonem. Ut commune similique tation magna theophrastus mel, in cum. Expetendis sed, vel et possit oportere. Cum at tantas percipit facilisi. Graeci semper blandit et per, ea harum exerci definitionem mei. Cu eam soleat nostro convenire, vis laudem. Alterum utroque cu, cum ponderum. Accommodare delicatissimi ut per ornatus omittantur an, eros magna eripuit te vis. Semper reprehendunt cum te. Quo laudem adipisci ea, ius choro phaedrum cu. Ludus tibique ocurreret ne pri, at noster iudicabit evertitur cotidieque per.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-033a277 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"033a277\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dab7b33 qodef-sticky-column--no\" data-id=\"dab7b33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88b0483 elementor-widget elementor-widget-qi_addons_for_elementor_blockquote\" data-id=\"88b0483\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-blockquote qodef-layout--inline qodef--custom-icon\">\n\t\t\t<h4 class=\"qodef-m-text\">\n\t\t\t\t\t\t\t<span class=\"qodef-m-icon\">\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 10 35\" style=\"stroke:none;\"><text style=\"font-size:30px;font-family:Cormorant-Regular, Cormorant;\" transform=\"translate(0 24.38)\">\u201c<\/text><\/svg>\t\t\t\t<\/span>\n\t\t\t\t\t\tI hope that in this year to come, you make mistakes. If you are making mistakes\u2026you\u2019re Doing Something. \u201c\t\t<\/h4>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d82cbd3 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"d82cbd3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-428e10f qodef-sticky-column--no\" data-id=\"428e10f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cea29cf elementor-widget elementor-widget-text-editor\" data-id=\"cea29cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alia mucius ex nam, ea facer liber usu, est aliquam eu platonem. Ut commune similique tation magna theophrastus mel, in cum. Expetendis sed, vel et possit oportere. Cum at tantas percipit facilisi. Graeci semper blandit et per, ea harum exerci definitionem mei. Cu eam soleat nostro convenire, vis laudem. Alterum utroque cu, cum ponderum. Accommodare delicatissimi ut per ornatus omittantur an, eros magna eripuit te vis. Semper reprehendunt cum te. Quo laudem adipisci ea, ius choro phaedrum cu. Ludus tibique ocurreret ne pri, at noster iudicabit evertitur cotidieque per.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb10c16 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"cb10c16\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-73677e4 qodef-sticky-column--no\" data-id=\"73677e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c0aab2 elementor-widget elementor-widget-image\" data-id=\"5c0aab2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1300\" height=\"867\" src=\"https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-img-1.jpg\" class=\"attachment-full size-full wp-image-1555\" alt=\"aa\" srcset=\"https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-img-1.jpg 1300w, https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-img-1-300x200.jpg 300w, https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-img-1-1024x683.jpg 1024w, https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-img-1-768x512.jpg 768w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1154b67 qodef-sticky-column--no\" data-id=\"1154b67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f98369 elementor-widget elementor-widget-image\" data-id=\"3f98369\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1300\" height=\"867\" src=\"https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-img-2.jpg\" class=\"attachment-full size-full wp-image-1556\" alt=\"aa\" srcset=\"https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-img-2.jpg 1300w, https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-img-2-300x200.jpg 300w, https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-img-2-1024x683.jpg 1024w, https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-img-2-768x512.jpg 768w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffe8a26 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"ffe8a26\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f50e558 qodef-sticky-column--no\" data-id=\"f50e558\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca975df elementor-widget elementor-widget-text-editor\" data-id=\"ca975df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>About the model<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9922490 elementor-widget elementor-widget-text-editor\" data-id=\"9922490\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ut commune similique tation magna theophrastus mel, in cum. Expetendis sed, vel et possit oportere. Cum at tantas percipit facilisi. Graeci semper blandit et per, ea harum exerci definitionem mei. Cu eam soleat nostro convenire, vis laudem. Alterum utroque cu, cum ponderum. Accommodare delicatissimi ut per ornatus omittantur an, eros magna eripuit te vis. Semper reprehendunt cum te. Quo laudem adipisci ea, ius choro phaedrum cu. Ludus tibique ocurreret ne pri, at noster iudicabit evertitur cotidieque per. Solet conceptam an quo. Ut tamquam elaboraret quo. Pri ut detraxit iudicabit efficiantur. Aeque vitae appetere eu est, duo at aeque explicari, laboramus maiestatis quo ex. Ad eam amet simul exerci, cum laudem tibique aliquando ei. Mel porro mucius persius at, illum officiis no ius.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bcfa9db elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"bcfa9db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3462cb1 qodef-sticky-column--no\" data-id=\"3462cb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a35140 elementor-widget elementor-widget-text-editor\" data-id=\"9a35140\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Pros and cons<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d89f70f elementor-widget elementor-widget-text-editor\" data-id=\"d89f70f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aeque vitae appetere eu est, duo at aeque explicari, laboramus maiestatis quo ex. Ad eam amet simul exerci, cum tibique aliquando ei. Mel porro mucius persius at, illum officiis no ius. Sea et\u00a0 copiosae euripidis, et elit ancillae eam, eos ex tation postulant liberavisse. Soleat audire cotidieque eum eu, dicat efficiendi duo in. Quo eu legere eligendi, sed ea atomorum efficiantur. Id quod dolorem duo, eu mel posse dolores detracto. Eu adhuc delenit gloriatur sed, ne omnesque quaerendum nam, dolorum perfecto et quo. Solum omnesque insolens mel in, ei meis sonet euripidis pro. Te adipisci atomorum assueverit mea, vocibus fierent intellegam eu per. Suavitate consequat vel et. Saperet graecis corpora est ex. No eripuit voluptatum est. Erant splendide incorrupte in ius, his ut quaeque voluptua neglegentur, oblique diceret cum ex. Veniam aperiam sea an, ei sale decore melius pro, mei sumo laudem ea.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d4f7de elementor-widget elementor-widget-text-editor\" data-id=\"2d4f7de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Et copiosae euripidis, et elit ancillae eam, eos ex tation postulant liberavisse. Soleat audire cotidieque eum eu, dicat efficiendi duo in. Solum omnesque insolens mel in, ei meis sonet euripidis pro. Te adipisci atomorum assueverit mea, vocibus fierent intellegam eu per. Suavitate consequat vel et. Saperet graecis corpora est ex. No eripuit voluptatum est. Erant splendide incorrupte in ius, his ut quaeque voluptua neglegentur, oblique diceret cum ex. Veniam aperiam sea an, ei sale decore melius pro, mei sumo laudem ea.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Alia mucius ex nam, ea facer liber usu, est aliquam eu platonem. Ut commune similique tation magna theophrastus mel, in cum. Expetendis sed, vel et possit oportere. Cum at tantas percipit facilisi. Graeci semper blandit et per, ea harum exerci definitionem mei. Cu eam soleat nostro convenire, vis laudem.<\/p>\n","protected":false},"author":1,"featured_media":1861,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[34,38,42,43],"class_list":["post-517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bays","tag-bay","tag-gorda","tag-sailing","tag-sea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Virgin gorda - Salty-Tour<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Virgin gorda - Salty-Tour\" \/>\n<meta property=\"og:description\" content=\"Alia mucius ex nam, ea facer liber usu, est aliquam eu platonem. Ut commune similique tation magna theophrastus mel, in cum. Expetendis sed, vel et possit oportere. Cum at tantas percipit facilisi. Graeci semper blandit et per, ea harum exerci definitionem mei. Cu eam soleat nostro convenire, vis laudem.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/\" \/>\n<meta property=\"og:site_name\" content=\"Salty-Tour\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-09T07:40:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/qi107.qodeinteractive.com\/wp-content\/uploads\/2021\/09\/blog-img-1.jpg\" \/>\n<meta name=\"author\" content=\"Alex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/\"},\"author\":{\"name\":\"Alex\",\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/#\\\/schema\\\/person\\\/51ff5cc4c7cc64011013c0db5ed4f79d\"},\"headline\":\"Virgin gorda\",\"datePublished\":\"2021-09-09T07:40:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/\"},\"wordCount\":553,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salty-tour.fr\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/blog-featured-img-06.jpg\",\"keywords\":[\"bay\",\"gorda\",\"sailing\",\"sea\"],\"articleSection\":[\"Bays\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/\",\"url\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/\",\"name\":\"Virgin gorda - Salty-Tour\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salty-tour.fr\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/blog-featured-img-06.jpg\",\"datePublished\":\"2021-09-09T07:40:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/#\\\/schema\\\/person\\\/51ff5cc4c7cc64011013c0db5ed4f79d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salty-tour.fr\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/blog-featured-img-06.jpg\",\"contentUrl\":\"https:\\\/\\\/salty-tour.fr\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/blog-featured-img-06.jpg\",\"width\":1300,\"height\":800,\"caption\":\"jj\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/2021\\\/09\\\/09\\\/virgin-gorda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salty-tour.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Virgin gorda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/#website\",\"url\":\"https:\\\/\\\/salty-tour.fr\\\/\",\"name\":\"Salty-Tour\",\"description\":\"Excursion en catamaran aux Saintes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salty-tour.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/salty-tour.fr\\\/#\\\/schema\\\/person\\\/51ff5cc4c7cc64011013c0db5ed4f79d\",\"name\":\"Alex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1e013db87d288f81c4bbb54356b19ab733c5a92078c54037d0edf2bd0cdeec2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1e013db87d288f81c4bbb54356b19ab733c5a92078c54037d0edf2bd0cdeec2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1e013db87d288f81c4bbb54356b19ab733c5a92078c54037d0edf2bd0cdeec2?s=96&d=mm&r=g\",\"caption\":\"Alex\"},\"sameAs\":[\"https:\\\/\\\/salty-tour.fr\"],\"url\":\"https:\\\/\\\/salty-tour.fr\\\/index.php\\\/author\\\/alex\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Virgin gorda - Salty-Tour","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/","og_locale":"fr_FR","og_type":"article","og_title":"Virgin gorda - Salty-Tour","og_description":"Alia mucius ex nam, ea facer liber usu, est aliquam eu platonem. Ut commune similique tation magna theophrastus mel, in cum. Expetendis sed, vel et possit oportere. Cum at tantas percipit facilisi. Graeci semper blandit et per, ea harum exerci definitionem mei. Cu eam soleat nostro convenire, vis laudem.","og_url":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/","og_site_name":"Salty-Tour","article_published_time":"2021-09-09T07:40:47+00:00","og_image":[{"url":"https:\/\/qi107.qodeinteractive.com\/wp-content\/uploads\/2021\/09\/blog-img-1.jpg","type":"","width":"","height":""}],"author":"Alex","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Alex","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/#article","isPartOf":{"@id":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/"},"author":{"name":"Alex","@id":"https:\/\/salty-tour.fr\/#\/schema\/person\/51ff5cc4c7cc64011013c0db5ed4f79d"},"headline":"Virgin gorda","datePublished":"2021-09-09T07:40:47+00:00","mainEntityOfPage":{"@id":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/"},"wordCount":553,"commentCount":0,"image":{"@id":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/#primaryimage"},"thumbnailUrl":"https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-featured-img-06.jpg","keywords":["bay","gorda","sailing","sea"],"articleSection":["Bays"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/","url":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/","name":"Virgin gorda - Salty-Tour","isPartOf":{"@id":"https:\/\/salty-tour.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/#primaryimage"},"image":{"@id":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/#primaryimage"},"thumbnailUrl":"https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-featured-img-06.jpg","datePublished":"2021-09-09T07:40:47+00:00","author":{"@id":"https:\/\/salty-tour.fr\/#\/schema\/person\/51ff5cc4c7cc64011013c0db5ed4f79d"},"breadcrumb":{"@id":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/#primaryimage","url":"https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-featured-img-06.jpg","contentUrl":"https:\/\/salty-tour.fr\/wp-content\/uploads\/2021\/09\/blog-featured-img-06.jpg","width":1300,"height":800,"caption":"jj"},{"@type":"BreadcrumbList","@id":"https:\/\/salty-tour.fr\/index.php\/2021\/09\/09\/virgin-gorda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salty-tour.fr\/"},{"@type":"ListItem","position":2,"name":"Virgin gorda"}]},{"@type":"WebSite","@id":"https:\/\/salty-tour.fr\/#website","url":"https:\/\/salty-tour.fr\/","name":"Salty-Tour","description":"Excursion en catamaran aux Saintes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salty-tour.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/salty-tour.fr\/#\/schema\/person\/51ff5cc4c7cc64011013c0db5ed4f79d","name":"Alex","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f1e013db87d288f81c4bbb54356b19ab733c5a92078c54037d0edf2bd0cdeec2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1e013db87d288f81c4bbb54356b19ab733c5a92078c54037d0edf2bd0cdeec2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1e013db87d288f81c4bbb54356b19ab733c5a92078c54037d0edf2bd0cdeec2?s=96&d=mm&r=g","caption":"Alex"},"sameAs":["https:\/\/salty-tour.fr"],"url":"https:\/\/salty-tour.fr\/index.php\/author\/alex\/"}]}},"_links":{"self":[{"href":"https:\/\/salty-tour.fr\/index.php\/wp-json\/wp\/v2\/posts\/517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salty-tour.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salty-tour.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salty-tour.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/salty-tour.fr\/index.php\/wp-json\/wp\/v2\/comments?post=517"}],"version-history":[{"count":0,"href":"https:\/\/salty-tour.fr\/index.php\/wp-json\/wp\/v2\/posts\/517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salty-tour.fr\/index.php\/wp-json\/wp\/v2\/media\/1861"}],"wp:attachment":[{"href":"https:\/\/salty-tour.fr\/index.php\/wp-json\/wp\/v2\/media?parent=517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salty-tour.fr\/index.php\/wp-json\/wp\/v2\/categories?post=517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salty-tour.fr\/index.php\/wp-json\/wp\/v2\/tags?post=517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}